{"id":7642,"date":"2014-07-24T22:04:22","date_gmt":"2014-07-25T01:04:22","guid":{"rendered":"https:\/\/deportivadigital.com.ar\/v2\/fundemur-a-campeon-de-futsal\/"},"modified":"2014-07-24T22:04:22","modified_gmt":"2014-07-25T01:04:22","slug":"fundemur-a-campeon-de-futsal","status":"publish","type":"post","link":"https:\/\/deportivadigital.com.ar\/v2\/fundemur-a-campeon-de-futsal\/","title":{"rendered":"Fundemur \u00abA\u00bb campe\u00f3n de Futsal"},"content":{"rendered":"<p>Futsal:<br \/>El pasado fin de semana se disput\u00f3 en el gimnasio cubierto del <strong>Polideportivo Municipal N2<\/strong> un torneo de <strong>futsal<\/strong> organizado por la <strong>Escuela de Futsal de la Fundaci\u00f3n Deportiva Municipal.<\/strong><br \/>Del mismo participaron seis equipos de la ciudad: Fundemur \u00abA\u00bb, Fundemur \u00abB\u00bb, Argentinos Juniors, Estudiantes, Banda Norte y Deportivo R\u00edo Cuarto.<br \/>Luego de disputar la fase de grupos, los cuatro mejores equipos se clasificaron a las semifinales, donde en el primero de los partidos Fundemur \u00abA\u00bb venci\u00f3 a Deportivo R\u00edo Cuarto; mientras que en el segundo encuentro, Argentinos Juniors se impuso a Estudiantes 6 a 4.<br \/>En la final, luego de un intenso y vibrante partido, Fundemur \u00abA\u00bb y Argentinos Juniors igualaron 3 a 3 en el tiempo reglamentario, logrando el t\u00edtulo el representativo de Fundemur \u00abA\u00bb al imponerse en los penales por 4 a 2.<br \/>Cabe destacar el crecimiento que esta disciplina est\u00e1 teniendo en la ciudad, apoyada adem\u00e1s por la Escuela de Futsal de Fundemur, que funciona bajo la orden de sus coordinadores Guillermo Nu\u00f1ez, Ariel G\u00f3mez y Carlos Bulacio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Futsal:El pasado fin de semana se disput\u00f3 en el gimnasio cubierto del Polideportivo Municipal N2 un torneo de futsal organizado por la Escuela de Futsal de la Fundaci\u00f3n Deportiva Municipal.Del mismo participaron seis equipos de la ciudad: Fundemur \u00abA\u00bb, Fundemur \u00abB\u00bb, Argentinos Juniors, Estudiantes, Banda Norte y Deportivo R\u00edo Cuarto.Luego de disputar la fase de &hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[98],"tags":[],"class_list":["post-7642","post","type-post","status-publish","format-standard","hentry","category-futbol"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/posts\/7642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/comments?post=7642"}],"version-history":[{"count":0,"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/posts\/7642\/revisions"}],"wp:attachment":[{"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/media?parent=7642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/categories?post=7642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/tags?post=7642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}