{"id":7342,"date":"2014-05-12T13:59:01","date_gmt":"2014-05-12T16:59:01","guid":{"rendered":"https:\/\/deportivadigital.com.ar\/v2\/ateneo-con-ayuda-derroto-a-juventud-unida-rio-cuarto\/"},"modified":"2014-05-12T13:59:01","modified_gmt":"2014-05-12T16:59:01","slug":"ateneo-con-ayuda-derroto-a-juventud-unida-rio-cuarto","status":"publish","type":"post","link":"https:\/\/deportivadigital.com.ar\/v2\/ateneo-con-ayuda-derroto-a-juventud-unida-rio-cuarto\/","title":{"rendered":"Ateneo con ayuda derrot\u00f3 a Juventud Unida R\u00edo Cuarto"},"content":{"rendered":"<p>Ateneo sigue de racha. En R\u00edo Cuarto, en el mediod\u00eda del domingo, derrot\u00f3 a Juventud Unida por 2 a 1 y ahora va por el cl\u00e1sico<\/p>\n<p>Con muestras de juego colectivo y sacando \u00abchapa\u00bb con sus individualidades, Ateneo Vecinos barrio Argentino de General Cabrera le gan\u00f3 ayer por 2 a 1 a Juventud Unida de R\u00edo Cuarto y se mantiene entre los equipos que estar\u00e1n en la lucha por el primer lugar en la zona Norte del torneo Apertura de primera divisi\u00f3n que organiza la Liga Regional de Futbol de R\u00edo Cuarto.<br \/>Nada nuevo bajo el sol \u2013que ayer estuvo ausente en el mediod\u00eda riocuartense- para justificar la victoria del equipo de Mariano Dulla. Dos aciertos de Maximiliano Foggia, uno en cada per\u00edodo, el descuento de Roberto Vissio cuando el partido ya conclu\u00eda, fueron las principales incidencias de un partido que tuvo s\u00f3lo pasajes de buen juego y que se observaron principalmente en los primeros cuarenta y cinco minutos.<br \/>\u00bfPor qu\u00e9 gan\u00f3 Ateneo? La explicaci\u00f3n se debe encontrar en la muy floja tarea de la l\u00ednea defensiva de Juventud Unida y a la \u00abchapa\u00bb que tiene en varias individualidades el elenco cabrerense.<br \/>Tan es as\u00ed, que cuando a\u00fan el partido no estaba armado y se jugaban 180 segundo, sali\u00f3 un pelotazo largo para el \u00abTen\u00bb L\u00f3pez, el delantero le gan\u00f3 la espalda a Juan \u00c1lvarez, envi\u00f3 el centro atr\u00e1s, apareci\u00f3 por el medio del \u00e1rea Maximiliano Fogia, quien se anticip\u00f3 al cierre de los centrales y toc\u00f3 la pelota al gol.<br \/>La ventaja le dio tranquilidad a Ateneo que abus\u00f3 de la confianza para salir jugando la pelota a raz de piso, pero Juventud se las ingeni\u00f3 para cortar esa circulaci\u00f3n y, en lo que va del ascenso, se pudieron ver los mejores minutos del elenco riocuartense.<br \/><span style=\"text-decoration: underline;\">Si los dirigidos por Julio Titarelli no llegaron al empate fue porque<strong> Pablo Bonetto tuvo dos muy buenas<\/strong><\/span> i<span style=\"text-decoration: underline;\">ntervenciones, en una de ellas le sac\u00f3 una pelota que ten\u00eda de red enviada por Gonzalo L\u00f3pez, y en otras tres, los delanteros del elenco local no estuvieron finos en la definici\u00f3n.<\/span><br \/><span style=\"text-decoration: underline;\">E<\/span>l triunfo parcial con el que se fueron al descanso hizo que en el complemento se esperara una mayor presi\u00f3n de los locales y un crecimiento de la visita.<br \/>Lo que sucedi\u00f3 fue que Ateneo se hizo due\u00f1o de la pelota, gener\u00f3 espacios ante un equipo que no encontraba c\u00f3mo hacer pie en el campo de juego y en consecuencia no extra\u00f1\u00f3 que cuando promediara la etapa Maximiliano Foggia apareciera solo a la espalda de Izaguirre y estableciera el dos a cero.<br \/>Cuesta arriba para los locales y lucimiento para la visita. Creci\u00f3 la figura del arquero Luciano Cometto que impidi\u00f3 la ca\u00edda de su arco en al menos dos claras situaciones que gener\u00f3 la visita.<br \/>Cuando el partido entraba en tiempo adicionado, el exceso de confianza de la visita en salir jugando la pelota desde su propio arco, hizo que Jofr\u00e9 ganara el bal\u00f3n, que le qued\u00f3 a Vissio, quien r\u00e1pidamente encar\u00f3 el \u00e1rea visitante y marc\u00f3 el descuento.<br \/>No qued\u00f3 tiempo para m\u00e1s. Ateneo se llev\u00f3 tres puntos muy importantes y ahora ya piensa en el cl\u00e1sico ante Acci\u00f3n Juvenil de General Deheza que ser\u00e1 el pr\u00f3ximo domingo. Juventud Unida sigue sintiendo el peso de adaptaci\u00f3n al c\u00edrculo superior del f\u00fatbol regional y sigue sin poder sumar en su cancha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ateneo sigue de racha. En R\u00edo Cuarto, en el mediod\u00eda del domingo, derrot\u00f3 a Juventud Unida por 2 a 1 y ahora va por el cl\u00e1sico Con muestras de juego colectivo y sacando \u00abchapa\u00bb con sus individualidades, Ateneo Vecinos barrio Argentino de General Cabrera le gan\u00f3 ayer por 2 a 1 a Juventud Unida de &hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[113],"tags":[],"class_list":["post-7342","post","type-post","status-publish","format-standard","hentry","category-liga-regional-rio-cuarto"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/posts\/7342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/comments?post=7342"}],"version-history":[{"count":0,"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/posts\/7342\/revisions"}],"wp:attachment":[{"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/media?parent=7342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/categories?post=7342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/tags?post=7342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}