{"id":7191,"date":"2014-04-09T03:05:21","date_gmt":"2014-04-09T06:05:21","guid":{"rendered":"https:\/\/deportivadigital.com.ar\/v2\/tdi-ya-esta-el-rival-y-la-fecha\/"},"modified":"2014-04-09T03:05:21","modified_gmt":"2014-04-09T06:05:21","slug":"tdi-ya-esta-el-rival-y-la-fecha","status":"publish","type":"post","link":"https:\/\/deportivadigital.com.ar\/v2\/tdi-ya-esta-el-rival-y-la-fecha\/","title":{"rendered":"TDI. Ya est\u00e1 el rival y la fecha"},"content":{"rendered":"<p><img decoding=\"async\" style=\"margin: 5px; float: left;\" src=\"images\/stories\/futbol\/ArgentinoB\/AtenasII.jpg\" alt=\"AtenasII\" \/>El Consejo Federal dio a conocer los cruces finales del <strong>TDI,<\/strong> <strong>Atenas enfrentar\u00e1 a Sports Luj\u00e1n de Mendoza<\/strong>. El primer partido el 20 de abril se jugar\u00e1 en Luj\u00e1n de Cuyo, mientras que la revancha ser\u00e1 el 27 de abril en R\u00edo Cuarto.<\/p>\n<p>  <!--more-->  <\/p>\n<p>&nbsp;<\/p>\n<p>Mucho se especulaba con la posibilidad de jugar con equipos m\u00e1s cercanos, como 9 de Julio de R\u00edo Tercero o bien San Mart\u00edn de Merlo, pero una vez m\u00e1s el Consejo Federal hace mirar a los equipos del sur de C\u00f3rdoba rumbo a cuyo.<\/p>\n<p>Luj\u00e1n Sports inici\u00f3 el TDI como uno de los equipos de la provincia de Mendoza con aspiraciones a pelear el ascenso y el conjunto que dirige Juan Pablo Videla lo fue confirmando en el transcurrir de los partidos.<\/p>\n<p>El \u00abgranate\u00bb disput\u00f3 en la primera fase la zona 60, junto con Cicles Club Lavalle y Deportivo La Dormida. En la primera fecha gan\u00f3 de visitante ante Cicles por 1 a 0, en la segunda qued\u00f3 libre, en la tercera gole\u00f3 como local 5 a 0 a Deportivo La Dormida, en la cuarta venci\u00f3 a Cicles por 3 a 1 como local y se asegur\u00f3 el primer puesto.<\/p>\n<p>En el primer cruce de play off se enfrent\u00f3 a Atl\u00e9tico San Jos\u00e9 de Tupungato a quien super\u00f3 sin inconvenientes, en el primer partido se impuso por 4 a 1 como visitante y en la vuelta tambi\u00e9n se impuso por 4 a 1.<\/p>\n<p>En las semifinales se volvi\u00f3 a enfrentar a Cicles Club Lavalle y gan\u00f3 en el primer partido como visitante por 3 a 1 y en la vuelta ante su p\u00fablico gan\u00f3 por 2 a 0 y asegur\u00f3 un lugar en la final. El \u00faltimo partido se disput\u00f3 ante un marco de 1200 personas aproximadamente.<\/p>\n<p>Los n\u00fameros de Luj\u00e1n Sports son interesantes ya que sum\u00f3 todos los puntos que disput\u00f3, marcha invicto y ni siquiera empat\u00f3. Aparece como un rival de cuidado para las aspiraciones de Atenas que llega con el \u00e1nimo bien arriba luego de dejar en el camino a un escollo a priori m\u00e1s complicado como Ateneo de Cabrera.<\/p>\n<p>La \u00faltima formaci\u00f3n de Luj\u00e1n Sports fue la siguiente: Marcos Tobar, Lautaro Valdivia, Cristian Campagnani, Dami\u00e1n L\u00e1zaro, Federico Lescano, Horacio Malinar, Nahuel Ibaceta, Pablo Dellarole, Ignacio Ruiz, Lucas Mart\u00ednez y Mauricio Ch\u00e1vez. DT: Juan Pablo Videla<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo Federal dio a conocer los cruces finales del TDI, Atenas enfrentar\u00e1 a Sports Luj\u00e1n de Mendoza. El primer partido el 20 de abril se jugar\u00e1 en Luj\u00e1n de Cuyo, mientras que la revancha ser\u00e1 el 27 de abril en R\u00edo Cuarto. &nbsp; Mucho se especulaba con la posibilidad de jugar con equipos m\u00e1s &hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[98],"tags":[],"class_list":["post-7191","post","type-post","status-publish","format-standard","hentry","category-futbol"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/posts\/7191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/comments?post=7191"}],"version-history":[{"count":0,"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/posts\/7191\/revisions"}],"wp:attachment":[{"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/media?parent=7191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/categories?post=7191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deportivadigital.com.ar\/v2\/wp-json\/wp\/v2\/tags?post=7191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}